{"id":21159,"date":"2022-05-23T12:12:48","date_gmt":"2022-05-23T09:12:48","guid":{"rendered":"http:\/\/simplytr.net\/pcr-test-requirement-will-be-avoided-from-16-countries\/"},"modified":"2022-05-23T12:12:48","modified_gmt":"2022-05-23T09:12:48","slug":"16-%e4%b8%aa%e5%9b%bd%e5%ae%b6-%e5%9c%b0%e5%8c%ba%e5%b0%86%e9%81%bf%e5%85%8d-pcr-%e6%a3%80%e6%b5%8b%e8%a6%81%e6%b1%82","status":"publish","type":"post","link":"https:\/\/simplytr.net\/zh\/16-%e4%b8%aa%e5%9b%bd%e5%ae%b6-%e5%9c%b0%e5%8c%ba%e5%b0%86%e9%81%bf%e5%85%8d-pcr-%e6%a3%80%e6%b5%8b%e8%a6%81%e6%b1%82\/","title":{"rendered":"16 \u4e2a\u56fd\u5bb6\u5c06\u53d6\u6d88 PCR \u68c0\u6d4b\u8981\u6c42"},"content":{"rendered":"<p>\u8fc4\u4eca\u4e3a\u6b62\uff0c\u6839\u636e\u536b\u751f\u90e8\u548c\u51a0\u72b6\u75c5\u6bd2\u79d1\u5b66\u59d4\u5458\u4f1a\u7684\u5efa\u8bae\u4ee5\u53ca\u603b\u7edf\u96f7\u6770\u666e\u00b7\u5854\u4f0a\u666e\u00b7\u57c3\u5c14\u591a\u5b89\u7684\u6307\u793a\uff0c\u5df2\u7ecf\u91c7\u53d6\u4e86\u8bb8\u591a\u63aa\u65bd\uff0c\u4ee5\u6700\u5927\u7a0b\u5ea6\u5730\u51cf\u5c11\u51a0\u72b6\u75c5\u6bd2\u6d41\u884c\u7684\u8d1f\u9762\u5f71\u54cd\u3002\u4e16\u754c\uff0c\u5173\u4e8e\u516c\u5171\u536b\u751f\u3002&nbsp;<\/p>\n<p>\u4ece\u56fd\u5916\u62b5\u8fbe\u571f\u8033\u5176\u7684\u4e58\u5ba2\u5fc5\u987b\u63d0\u4ea4\u822a\u73ed\u8d77\u98de\u524d 72 \u5c0f\u65f6\u8fdb\u884c\u7684 PCR \u68c0\u6d4b\u3002\u6839\u636e\u65b0\u51b3\u5b9a\uff0c\u6765\u81ea 16 \u4e2a\u56fd\u5bb6\u7684\u4e58\u5ba2\u5c06\u4e0d\u518d\u88ab\u8981\u6c42\u8fdb\u884c PCR \u68c0\u6d4b\u3002&nbsp;<\/p>\n<blockquote>\n<p><span style=\"font-family:Arial,Helvetica,sans-serif\"><u><em><strong>\u571f\u8033\u5176\u822a\u7a7a\u5b98\u65b9\u7f51\u7ad9\u4e0a\u6807\u9898\u4e3a\u201c\u524d\u5f80\u571f\u8033\u5176\u201d\u7684\u90e8\u5206\u58f0\u660e\u4e2d\uff0c\u201c\u81ea 2021 \u5e74 5 \u6708 15 \u65e5\u8d77\uff1b<\/strong><\/em><\/u><\/span><\/p>\n<p><strong><span style=\"font-family:Arial,Helvetica,sans-serif\">* \u9999\u6e2f\uff0c<br \/>\n* \u4e2d\u56fd\uff0c<br \/>\n* \u53f0\u6e7e\uff0c<br \/>\n* \u8d8a\u5357\uff0c<br \/>\n* \u6fb3\u5927\u5229\u4e9a\uff0c<br \/>\n* \u65b0\u897f\u5170\uff0c<br \/>\n* \u65b0\u52a0\u5761\uff0c<br \/>\n* \u6cf0\u56fd\uff0c<br \/>\n* \u97e9\u56fd\uff0c<br \/>\n* \u4ee5\u8272\u5217\uff0c<br \/>\n* \u65e5\u672c\uff0c<br \/>\n* \u82f1\u56fd\uff0c<br \/>\n* \u62c9\u8131\u7ef4\u4e9a,<br \/>\n* \u5362\u68ee\u5821,<br \/>\n* \u4e4c\u514b\u5170<br \/>\n* \u6765\u81ea\u7231\u6c99\u5c3c\u4e9a<\/span><\/strong><\/p>\n<p><span style=\"font-family:Arial,Helvetica,sans-serif\">\u6765\u571f\u8033\u5176\u7684\u4eba\u5728\u8fdb\u5165\u571f\u8033\u5176\u65f6\u4e0d\u4f1a\u88ab\u8981\u6c42\u8fdb\u884c PCR \u68c0\u6d4b\u3002\u201d<\/span><br \/>\n&nbsp;<\/p>\n<\/blockquote>\n<p>                                                                            <img decoding=\"async\" src=\"\/Attachments\/Blog\/171\/98b13bf7-0ff8-4eaf-8046-67672e92bb0f.jpeg\" width=\"100%\" style=\"margin-top:15px; border:dotted 1px grey;\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Many measures have been taken so far, in line with  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[374,364,370,375,442,412,432,414,417,411,415,423,439,434,430,437,425,429,431,436,433,438,422,413,416,360,376,355,361,365,369,368,362,366,356,451,359,371,358,467,367,363,357,372,373,427,426,421,468,428,424,440,435,441],"class_list":["post-21159","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-apply-for-turkish-residence-permit","tag-apply-for-turkish-residence-permit-online","tag-apply-for-turkish-residency","tag-documents-needed-for-turkish-residence-permit","tag-getting-work-permit-in-turkey","tag-hsbc-turkey-open-an-account","tag-independent-work-permit-turkey","tag-open-a-turkish-bank-account-online","tag-open-account-ziraat-bank","tag-open-bank-account-turkey","tag-open-bank-account-turkey-non-resident","tag-renewing-residence-permit-turkey","tag-self-employed-visa-turkey","tag-turkey-work-permit-for-indian","tag-turkey-work-permit-for-pakistani","tag-turkey-work-permit-processing-time","tag-turkey-work-permit-requirements","tag-turkey-work-permit-visa","tag-turkey-work-permit-visa-for-bangladeshi","tag-turkey-work-permit-visa-for-indian","tag-turkey-work-permit-visa-for-pakistani","tag-turkey-work-permit-visa-for-pakistani-2021","tag-turkey-work-visa","tag-turkish-bank-account-for-foreigners","tag-turkish-online-bank-account","tag-turkish-permanent-residence","tag-turkish-permit","tag-turkish-residence-permit","tag-turkish-residence-permit-application","tag-turkish-residence-permit-application-form","tag-turkish-residence-permit-appointment","tag-turkish-residence-permit-appointment-online","tag-turkish-residence-permit-cost","tag-turkish-residence-permit-new-rules-2020","tag-turkish-residence-permit-new-rules-2021","tag-turkish-residence-permit-new-rules-2022","tag-turkish-residence-permit-renewal","tag-turkish-residence-permit-renewal-2020","tag-turkish-residence-permit-renewal-2021","tag-turkish-residence-permit-renewal-2022","tag-turkish-residence-permit-requirements","tag-turkish-residence-permit-tracking","tag-turkish-residency","tag-turkish-residency-application","tag-turkish-tourist-residence-permit","tag-work-permit-application-turkey","tag-work-permit-in-turkey-2021","tag-work-permit-turkey","tag-work-permit-turkey-2019","tag-work-permit-turkey-2020","tag-work-permit-turkey-2021","tag-work-permit-turkey-2022","tag-work-permit-visa-for-turkey-from-pakistan","tag-work-visa-in-turkey-requirements"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/posts\/21159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/comments?post=21159"}],"version-history":[{"count":0,"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/posts\/21159\/revisions"}],"wp:attachment":[{"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/media?parent=21159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/categories?post=21159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simplytr.net\/zh\/wp-json\/wp\/v2\/tags?post=21159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}